{"id":13040,"date":"2017-03-01T14:56:46","date_gmt":"2017-03-01T13:56:46","guid":{"rendered":"https:\/\/ab-marineservice.com\/product\/impellerpumpe-northern-lights-nl-25-15405\/"},"modified":"2025-06-01T17:28:07","modified_gmt":"2025-06-01T15:28:07","slug":"impellerpumpe-northern-lights-m864-m984-serie-kuhlwasserpumpe","status":"publish","type":"product","link":"https:\/\/ab-marineservice.com\/de\/produkt\/impellerpumpe-northern-lights-m864-m984-serie-kuhlwasserpumpe\/","title":{"rendered":"Impellerpumpe  Northern Lights M864, M984 Serie K\u00fchlwasserpumpe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Die Pumpe wird inklusive Laufrad geliefert.<\/strong><\/p>\n<p>Diese K\u00fchlwasserpumpe f\u00fcr die Northern Lights-Schiffsmotoren ist ideal f\u00fcr den Ersatz der originalen Johnson-, Jabsco-, Ancor- oder Sherwood-Impellerpumpe. Die hochwertige und h\u00e4ufig verbesserte Version des Originals bietet eine zuverl\u00e4ssige L\u00f6sung f\u00fcr den Austausch Ihrer Bootspumpe. Alle Teile wie der Impeller und die innere Verschlei\u00dfteile sind die gleichen wie die Originalversion f\u00fcr Wartung oder \u00dcberholung, sodass Sie immer noch \u00fcberall hingehen k\u00f6nnen.<\/p>\n<p>Diese K\u00fchlwasserpumpe passt u.a. auf die folgenden Northern Lights-Schiffsmotoren <strong>M864K, M864W, M864W3, M964, M984K, M984W<\/strong><\/p>\n<p>Ersetzt:: NORTHERN LIGHTS <strong> NL-25-15405 <\/strong><\/p>\n<p>Bei Fragen zu diesem Produkt, dieser Teile oder dem Typ oder der Anwendung wenden Sie sich bitte an uns.<br \/>\nEs kann verschiedene Typen oder Nummern geben, die auch zu diesem K\u00fchlpumpentyp passen.<\/p>\n","protected":false},"featured_media":12263,"comment_status":"open","ping_status":"closed","template":"","meta":[],"location":[3906],"product_brand":[28201],"product_cat":[1316,1320,1335],"product_tag":[],"class_list":{"0":"post-13040","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"location-dintra","7":"product_brand-jmp-u-s-a-marine","8":"product_cat-impellerpumpen","9":"product_cat-impellerpumpen-motorspezifisch","10":"product_cat-northern-lights-de","11":"product_shipping_class-paket-0-10-kg","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","locations":[{"id":3906,"name":"Dintra","slug":"dintra","quantity":""}],"_links":{"self":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product\/13040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/comments?post=13040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media\/12263"}],"wp:attachment":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media?parent=13040"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/location?post=13040"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_brand?post=13040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_cat?post=13040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_tag?post=13040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}