{"id":445468,"date":"2026-07-02T14:38:42","date_gmt":"2026-07-02T12:38:42","guid":{"rendered":"https:\/\/ab-marineservice.com\/?post_type=product&#038;p=445468"},"modified":"2026-07-07T17:23:00","modified_gmt":"2026-07-07T15:23:00","slug":"volvo-penta-xact-bedienkabel-22-ft-671-m-21407235","status":"publish","type":"product","link":"https:\/\/ab-marineservice.com\/de\/produkt\/volvo-penta-xact-bedienkabel-22-ft-671-m-21407235\/","title":{"rendered":"Volvo Penta Xact Bedienkabel, 22 ft \/ 6,71 m &#8211;  21407235"},"content":{"rendered":"<p><strong>Produktinformationen:<\/strong><br \/>\nVolvo Penta Xact-Bedienkabel sind f\u00fcr eine besonders leichtg\u00e4ngige und pr\u00e4zise Gas- und Schaltbet\u00e4tigung ausgelegt und reduzieren gleichzeitig das Spiel in der Steuerung. Alle Anschl\u00fcsse bestehen aus Edelstahl und vernickeltem Messing. Der vollst\u00e4ndig aus Edelstahl gefertigte, gepanzerte Litzenkern bietet hohe Flexibilit\u00e4t und erm\u00f6glicht engere Biegeradien bei anspruchsvoller Kabelf\u00fchrung.<\/p>\n<p>Es ist sehr wichtig, die richtige Kabell\u00e4nge auszuw\u00e4hlen. Weniger Biegungen sorgen f\u00fcr eine bessere Funktion und l\u00e4ngere Lebensdauer. Messen Sie den Abstand zwischen der Bedienungseinheit und den Anschl\u00fcssen an Motor\/Getriebe m\u00f6glichst gerade. F\u00fcr jede Biegung ist ein Radius von 200 mm einzurechnen. Berechnen Sie die Kabell\u00e4nge wie in der Abbildung dargestellt: L = A + B + 200 mm. Liegt das Ma\u00df zwischen zwei Standardl\u00e4ngen, w\u00e4hlen Sie immer das l\u00e4ngere Kabel. Die Kabel d\u00fcrfen nicht gek\u00fcrzt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Volvo Penta Xact-Bedienkabel 21407235 ist ein originales reibungsarmes Bedienkabel mit einer L\u00e4nge von 22 ft (6,71 m) f\u00fcr eine leichtg\u00e4ngige Gas- und Schaltbet\u00e4tigung. Dank des gepanzerten Edelstahlkerns sowie hochwertiger Anschl\u00fcsse aus Edelstahl und vernickeltem Messing werden Spiel und Bedienwiderstand auf ein Minimum reduziert. Dadurch l\u00e4sst sich der Motor auch bei komplexer Kabelf\u00fchrung oder beengten Motorr\u00e4umen pr\u00e4ziser und leichter bedienen.<\/p>\n<h4>Wichtigste Merkmale und Vorteile:<\/h4>\n<p><strong>Geringe Reibung:<\/strong> Sorgt f\u00fcr eine leichtg\u00e4ngige und pr\u00e4zise Gas- und Schaltbet\u00e4tigung.<br \/>\n<strong>Weniger Spiel:<\/strong> Verbessert die Kontrolle \u00fcber Motor und Getriebe.<br \/>\n<strong>22 ft (6,71 m) L\u00e4nge:<\/strong> Geeignet f\u00fcr kompakte Installationen.<br \/>\n<strong>Gepanzerter Edelstahlkern:<\/strong> Bietet hohe Flexibilit\u00e4t und lange Lebensdauer.<br \/>\n<strong>Anschl\u00fcsse aus Edelstahl und vernickeltem Messing:<\/strong> Korrosionsbest\u00e4ndig f\u00fcr den maritimen Einsatz.<br \/>\n<strong>F\u00fcr enge Kabelf\u00fchrungen geeignet:<\/strong> L\u00e4sst sich leichter durch enge Biegeradien verlegen als Standard-Bedienkabel.<br \/>\n<strong>Original Volvo Penta Teil:<\/strong> Garantiert perfekte Passform und zuverl\u00e4ssigen Betrieb.<\/p>\n","protected":false},"featured_media":445282,"comment_status":"open","ping_status":"closed","template":"","meta":[],"location":[],"product_brand":[25895],"product_cat":[1222,22116,2161,25753],"product_tag":[],"class_list":{"0":"post-445468","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-volvo-penta","7":"product_cat-motorteile","8":"product_cat-teile-nach-marke","9":"product_cat-motorenteile-volvo-penta","10":"product_cat-volvo-penta-bedienelemente","11":"product_shipping_class-paket-0-10-kg","13":"first","14":"onbackorder","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","locations":[],"_links":{"self":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product\/445468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/comments?post=445468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media\/445282"}],"wp:attachment":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media?parent=445468"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/location?post=445468"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_brand?post=445468"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_cat?post=445468"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_tag?post=445468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}