{"id":71303,"date":"2022-04-04T16:34:29","date_gmt":"2022-04-04T14:34:29","guid":{"rendered":"https:\/\/ab-marineservice.com\/?post_type=product&#038;p=71303"},"modified":"2026-07-06T15:25:14","modified_gmt":"2026-07-06T13:25:14","slug":"motorstutze-bis-35kg-shore-40-stich-100","status":"publish","type":"product","link":"https:\/\/ab-marineservice.com\/de\/produkt\/motorstutze-bis-35kg-shore-40-stich-100\/","title":{"rendered":"Motorst\u00fctze bis 35kg Shore 40 Stich 100"},"content":{"rendered":"<p>Dieser Typ Motorst\u00fctze ist ein kompakter Schwingungsd\u00e4mpfer mit hohem D\u00e4mpfungsverm\u00f6gen gegen gro\u00dfe Auslenkungen.<br \/>\nAufgrund der Konstruktion und des hohen D\u00e4mpfungsverm\u00f6gens ist dieser Typ Motorst\u00fctze sehr gut geeignet f\u00fcr z.B. 1 oder 2 Zylinder Dieselmotoren.<br \/>\nMotoren mit 1 oder 2 Zylindern haben in der Regel einen gr\u00f6\u00dferen Hubraum pro Zylinder und sind schwerer ausgef\u00fchrt. Dadurch werden Schwingungen st\u00e4rker und mit gr\u00f6\u00dferer Auslenkung.<\/p>\n<p>Durch den integrierten Fahrbegrenzer kann die Sto\u00dfbewegung um bis zu 5G reduziert werden.<br \/>\nSt\u00f6rende Schwingungen werden somit enorm begrenzt und beim Segeln auf ein angenehmes Ma\u00df reduziert.<\/p>\n<p>MD-Mountings eignen sich sehr gut f\u00fcr mobile \/ maritime Anwendungen.<br \/>\nDie H\u00f6he ist durch einen Stift verstellbar. Sie k\u00f6nnen zwischen Stiftgr\u00f6\u00dfe M12 oder Stiftgr\u00f6\u00dfe M16 w\u00e4hlen, diese k\u00f6nnen separat bestellt werden.<\/p>\n<p>Die richtige Motorst\u00fctze:<br \/>\nDie Bestimmung der richtigen Motorst\u00fctzen oder Schwingungsd\u00e4mpfer ist eine Wissenschaft f\u00fcr sich. Wenn die Daten Ihrer alten Motorst\u00fctze mit diesem Motorst\u00fctze \u00fcbereinstimmen, k\u00f6nnen Sie diese leicht finden und bestellen.<br \/>\nWenn Ihnen diese Informationen nicht vorliegen, raten wir Ihnen dringend, sich vor der Bestellung neuer Motorst\u00fctzen beraten zu lassen. Dies vermeidet Entt\u00e4uschungen und zus\u00e4tzliche Versandkosten.<\/p>\n<p>Ben\u00f6tigte Daten f\u00fcr die richtige Motorst\u00fctze:<br \/>\nMarke und Typ:<br \/>\nGewicht des Motors:<br \/>\nDie maximale Anzahl von Umdrehungen:<br \/>\nIst ein Drucklager montiert:<br \/>\nDie Leistung des Motors:<\/p>\n<p>Bei Fragen zu diesem Produkt, dieser Teile oder dem Typ oder der Anwendung wenden Sie sich bitte an uns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motorst\u00fctze zur optimalen D\u00e4mpfung von mittelgro\u00dfen Motoren.<br \/>\nMaximale Last pro St\u00fctze 35 kg.<br \/>\nGummih\u00e4rte 40 shore.<\/p>\n<p>10-IM-130-A-40<\/p>\n<p>A L\u00e4nge: 120 mm<br \/>\nB H\u00f6he: 34 mm<br \/>\nC Breite: 60 mm<br \/>\nD Stich: 100 mm<\/p>\n<p>Einstellung der Schwingungsd\u00e4mpfer: <a href=\"https:\/\/ab-marineservice.com\/wp-content\/uploads\/2025\/12\/Korrekte-Einstellung-von-flexiblen-Schwingungsdampfern-fur-einen-Schiffsmotor.pdf\">Bedingungen f\u00fcr die korrekte Einstellung<\/a><\/p>\n","protected":false},"featured_media":71308,"comment_status":"open","ping_status":"closed","template":"","meta":[],"location":[15440],"product_brand":[],"product_cat":[1222,1431,3977],"product_tag":[],"class_list":{"0":"post-71303","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"location-vce","7":"product_cat-motorteile","8":"product_cat-motorstutzen","9":"product_cat-motorstutzen-4-zylinder-max-60ps","10":"product_shipping_class-paket-0-10-kg","12":"first","13":"onbackorder","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","locations":[{"id":15440,"name":"VCE","slug":"vce","quantity":""}],"_links":{"self":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product\/71303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/comments?post=71303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media\/71308"}],"wp:attachment":[{"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/media?parent=71303"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/location?post=71303"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_brand?post=71303"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_cat?post=71303"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ab-marineservice.com\/de\/wp-json\/wp\/v2\/product_tag?post=71303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}